{"id":1369,"date":"2024-09-25T13:42:01","date_gmt":"2024-09-25T05:42:01","guid":{"rendered":"http:\/\/www.lctc-group.com\/?p=1369"},"modified":"2025-09-18T18:23:54","modified_gmt":"2025-09-18T10:23:54","slug":"chargeur-11kw-serie-h-installe-sur-un-lieu-de-travail-a-cologne-allemagne","status":"publish","type":"post","link":"https:\/\/www.lctc-group.com\/fr\/11kw-h-series-charger-installed-at-a-workplace-in-cologne-germany\/","title":{"rendered":"Chargeur de la s\u00e9rie H 11KW install\u00e9 sur un lieu de travail \u00e0 Cologne, en Allemagne,"},"content":{"rendered":"<p><img decoding=\"async\" id=\"1838759599389949952\" src=\"https:\/\/omo-oss-image.thefastimg.com\/portal-saas\/new2022062014104039585\/cms\/image\/755aa089-ade3-453f-8c61-af0751a5c4c2.jpg\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>S\u00e9rie \ud83d\udd0bh \ud83d\udccdCologne, Allemagne \ud83e\uddf0 lieu de travail \ud83d\udcc52023<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Un lieu de travail \u00e0 Cologne a am\u00e9lior\u00e9 ses installations de charge de v\u00e9hicule \u00e9lectrique (EV) avec l'installation d'un chargeur de la s\u00e9rie H 11 kW.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>D\u00e9fi<\/strong><br \/>\nL'entreprise visait \u00e0 fournir \u00e0 ses employ\u00e9s une option de charge fiable et efficace pour soutenir leur utilisation croissante de v\u00e9hicules \u00e9lectriques.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Solution<\/strong><br \/>\nEn 2023, le chargeur de la s\u00e9rie H 11kw a \u00e9t\u00e9 install\u00e9, offrant une solution de charge puissante et efficace adapt\u00e9e aux besoins en milieu de travail.<\/p>\n<p>\"Le Charger de la s\u00e9rie H a facilit\u00e9 la charge de nos employ\u00e9s de facturer leurs v\u00e9hicules \u00e9lectriques au travail. Il est rapide, pratique et s'int\u00e8gre parfaitement dans nos installations\", a d\u00e9clar\u00e9 le directeur des installations.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00c9tapes suivantes<\/strong><br \/>\nLe lieu de travail profite d\u00e9sormais des avantages d'avoir une solution de charge d\u00e9di\u00e9e, avec des plans pour encourager davantage d'employ\u00e9s \u00e0 passer aux v\u00e9hicules \u00e9lectriques.<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; \ud83d\udd0bH-series \u00a0 \u00a0\ud83d\udccdCologne, Germany\u00a0\u00a0\u00a0\u00a0\ud83e\uddf0\u00a0Workplace\u00a0 \u00a0\ud83d\udcc52023 &nbsp; A workplace in Cologne has upgraded its electric vehicle (EV) charging facilities with the installation of an H-Series 11kW charger. &nbsp; Challenge The company aimed to provide its employees with a reliable and efficient charging option to support their growing electric vehicle usage. They needed a solution that [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,34],"tags":[],"class_list":["post-1369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solutions","category-h-series"],"_links":{"self":[{"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/posts\/1369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/comments?post=1369"}],"version-history":[{"count":1,"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/posts\/1369\/revisions"}],"predecessor-version":[{"id":1371,"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/posts\/1369\/revisions\/1371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/media\/1370"}],"wp:attachment":[{"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/media?parent=1369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/categories?post=1369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lctc-group.com\/fr\/wp-json\/wp\/v2\/tags?post=1369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}